{"id":3167,"date":"2026-02-05T11:46:51","date_gmt":"2026-02-05T10:46:51","guid":{"rendered":"https:\/\/www.gruene-mkk.de\/?p=3167"},"modified":"2026-02-09T22:33:36","modified_gmt":"2026-02-09T21:33:36","slug":"austausch-gruene-sosse-politischer-aschermittwoch-in-bad-orb","status":"publish","type":"post","link":"https:\/\/www.gruene-mkk.de\/it\/austausch-gruene-sosse-politischer-aschermittwoch-in-bad-orb\/","title":{"rendered":"Salsa verde - Mercoled\u00ec politico delle ceneri a Bad Orb"},"content":{"rendered":"<p>Il <strong>18 febbraio 2026<\/strong> Alliance 90\/The Greens invita cordialmente tutte le parti interessate a: <strong>Mercoled\u00ec politico delle ceneri<\/strong> ins <strong>Caff\u00e8 Kowalski<\/strong> di Bad Orb. <\/p>\n\n\n\n<p>Come ospite speciale, \u00e8 atteso il membro del Bundestag Tarek Al-Wazir, che con i suoi molti anni di esperienza politica fornir\u00e0 impulsi importanti per la politica statale e federale attuale. Il programma \u00e8 completato dai contributi dei principali candidati alle prossime elezioni distrettuali, Philip Schinkel e Mahwish Iftikhar, che presentano le loro priorit\u00e0 politiche e cercano il dialogo con i presenti.<\/p>\n\n\n\n<p>L'evento \u00e8 aperto a cittadini, membri e sostenitori interessati a partecipare attivamente e discutere di politica verde sul campo.<\/p>\n\n\n\n<p>Poich\u00e9 il numero di posti a sedere \u00e8 limitato, non possiamo garantire un posto a sedere o cibo senza registrazione. Grazie per la comprensione.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Il 18 febbraio 2026, B\u00fcndnis 90\/Die Gr\u00fcnen invita cordialmente tutte le parti interessate al \"Mercoled\u00ec politico delle ceneri\" al Caf\u00e9 Kowalski di Bad Orb. Come ospite speciale, \u00e8 atteso il membro del Bundestag Tarek Al-Wazir, che, con la sua [...]<\/p>","protected":false},"author":-1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3167","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.gruene-mkk.de\/it\/wp-json\/wp\/v2\/posts\/3167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruene-mkk.de\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gruene-mkk.de\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/it\/wp-json\/wp\/v2\/comments?post=3167"}],"version-history":[{"count":5,"href":"https:\/\/www.gruene-mkk.de\/it\/wp-json\/wp\/v2\/posts\/3167\/revisions"}],"predecessor-version":[{"id":3248,"href":"https:\/\/www.gruene-mkk.de\/it\/wp-json\/wp\/v2\/posts\/3167\/revisions\/3248"}],"wp:attachment":[{"href":"https:\/\/www.gruene-mkk.de\/it\/wp-json\/wp\/v2\/media?parent=3167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/it\/wp-json\/wp\/v2\/categories?post=3167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/it\/wp-json\/wp\/v2\/tags?post=3167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}