{"id":1651,"date":"2023-06-05T09:22:07","date_gmt":"2023-06-05T07:22:07","guid":{"rendered":"https:\/\/www.gruene-mkk.de\/?p=1651"},"modified":"2023-06-05T09:24:39","modified_gmt":"2023-06-05T07:24:39","slug":"buergermeisterwahl-in-gelnhausen","status":"publish","type":"post","link":"https:\/\/www.gruene-mkk.de\/fr\/buergermeisterwahl-in-gelnhausen\/","title":{"rendered":"\u00c9lections municipales \u00e0 Gelnhausen"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Aujourd'hui, Gelnhausen a \u00e9t\u00e9 plac\u00e9e sous le signe d'une d\u00e9cision d\u00e9mocratique importante: Le second tour de l'\u00e9lection du maire. Deux candidats engag\u00e9s se sont soumis au vote des citoyens.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jakob M\u00e4hler, notre candidat de l'Alliance 90\/Les Verts dans le Main-Kinzig-Kreis, a men\u00e9 une campagne \u00e9lectorale remarquable.<br>Il s'est battu jusqu'au second tour et s'est battu pour chaque voix avec d\u00e9vouement, engagement et engagement personnel exceptionnel.<br>M\u00eame si le r\u00e9sultat n'a pas \u00e9t\u00e9 dans son sens aujourd'hui, la performance de Jacob est tr\u00e8s appr\u00e9ciable. Il a plac\u00e9 des th\u00e8mes importants au centre du d\u00e9bat et a ainsi donn\u00e9 une impulsion importante \u00e0 la politique urbaine.<br>C'est pourquoi nous remercions tout particuli\u00e8rement Jakob M\u00e4hler.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le m\u00eame temps, nous f\u00e9licitons chaleureusement Christian Litzinger de la CDU pour son \u00e9lection en tant que nouveau maire de Gelnhausen. Il lui reste \u00e0 souhaiter la force et la pers\u00e9v\u00e9rance n\u00e9cessaires pour exercer ce poste exigeant avec succ\u00e8s au cours des six prochaines ann\u00e9es.<br>Comme indiqu\u00e9 ce soir \u00e0 M. Litzinger, les Verts lui proposent une coop\u00e9ration constructive \u00e0 Gelnhausen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un grand merci \u00e0 tous les citoyens qui ont particip\u00e9 aux \u00e9lections, ainsi qu'\u00e0 tous les candidats pour une campagne \u00e9lectorale globalement \u00e9quitable. Nous nous concentrons maintenant sur le travail futur pour Gelnhausen et le cercle Main-Kinzig.<\/p>","protected":false},"excerpt":{"rendered":"<p>Aujourd'hui, Gelnhausen a \u00e9t\u00e9 plac\u00e9e sous le signe d'une d\u00e9cision d\u00e9mocratique importante: Le second tour de l'\u00e9lection du maire. Alors que \u2026<\/p>","protected":false},"author":-1,"featured_media":1652,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/posts\/1651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/comments?post=1651"}],"version-history":[{"count":1,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/posts\/1651\/revisions"}],"predecessor-version":[{"id":1653,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/posts\/1651\/revisions\/1653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/media\/1652"}],"wp:attachment":[{"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/media?parent=1651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/categories?post=1651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/tags?post=1651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}