{"id":1569,"date":"2023-02-17T12:14:07","date_gmt":"2023-02-17T11:14:07","guid":{"rendered":"https:\/\/www.gruene-mkk.de\/?p=1569"},"modified":"2023-02-18T15:45:10","modified_gmt":"2023-02-18T14:45:10","slug":"gemeinsame-pressemitteilung-zum-jahrestag-des-anschlages-in-hanau","status":"publish","type":"post","link":"https:\/\/www.gruene-mkk.de\/fr\/gemeinsame-pressemitteilung-zum-jahrestag-des-anschlages-in-hanau\/","title":{"rendered":"Communiqu\u00e9 de presse conjoint \u00e0 l'occasion de l'anniversaire de l'attentat de Hanau"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>L'attentat de Hanau ne doit jamais se reproduire<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Le Main-Kinzig vert: La lutte contre le racisme reste un d\u00e9fi de soci\u00e9t\u00e9<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le 19 f\u00e9vrier marque le troisi\u00e8me anniversaire de l'attentat raciste de Hanau: \u00abNous nous souvenons des victimes et nous nous tenons en pleine solidarit\u00e9 aux c\u00f4t\u00e9s des personnes touch\u00e9es et de leurs proches\u00bb, d\u00e9clarent les porte-parole du bureau du district des Verts Main-Kinzig, Emily Benatzky et Ahmet Cetiner, ainsi que le bureau du groupe parlementaire du district, Reiner Bousonville, Viola Ha\u00dfdenteufel et Jakob M\u00e4hler.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abCet anniversaire nous montre clairement que la lutte contre le racisme demeure une t\u00e2che qui incombe \u00e0 l\u2019ensemble de la soci\u00e9t\u00e9. En effet, outre la comm\u00e9moration des victimes de cet acte, les circonstances doivent continuer \u00e0 \u00eatre pleinement \u00e9lucid\u00e9es et trait\u00e9es.\u00bb \u00abNous esp\u00e9rons en particulier que la commission d\u2019enqu\u00eate du Landtag apportera les r\u00e9ponses appropri\u00e9es.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le racisme doit \u00eatre pris au s\u00e9rieux dans tous les domaines de la vie: \u00abL\u2019attentat de Hanau n\u2019a pas \u00e9t\u00e9 un cas isol\u00e9 de violence \u00e0 caract\u00e8re raciste. Le nombre d\u2019infractions recens\u00e9es est alarmant et le chiffre obscur par rapport au nombre officiel de la Conf\u00e9d\u00e9ration est probablement plusieurs fois plus \u00e9lev\u00e9.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par exemple, les r\u00e9sultats de l\u2019enqu\u00eate men\u00e9e par l\u2019AfD en Thuringe et en Saxe montrent que \u00ables propos x\u00e9nophobes et le racisme ouvertement exprim\u00e9 sont revenus dans certaines parties de la soci\u00e9t\u00e9. Cette situation est pr\u00e9occupante, mais elle montre \u00e9galement un manque d\u2019\u00e9ducation et de sensibilisation\u00bb, ont d\u00e9clar\u00e9 les repr\u00e9sentants des Verts.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est donc n\u00e9cessaire de se souvenir de l'acte de Hanau et de poursuivre la r\u00e9flexion politique, d\u00e9clare Mahwish Iftikhar, porte-parole du groupe des Verts pour les migrations et l'int\u00e9gration: \u00abLes personnes en deuil m\u00e9ritent d\u2019\u00eatre soutenues et entendues.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour cr\u00e9er des communaut\u00e9s s\u00fbres et inclusives, le racisme doit \u00eatre combattu de mani\u00e8re structurelle, institutionnelle et quotidienne: \u00abLes propos et actions racistes, antis\u00e9mites et fascistes n\u2019ont pas leur place dans notre monde. Nous avons besoin d'une politique de m\u00e9moire active pour relever les d\u00e9fis de la lutte contre le racisme. Nous devons cr\u00e9er une soci\u00e9t\u00e9 plurielle.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, les repr\u00e9sentants des Verts remercient le travail des proches et de l\u2019initiative du 19 f\u00e9vrier: \u00abIl s\u2019agit d\u2019un engagement soci\u00e9tal important en faveur de la tol\u00e9rance et de la coexistence pacifique. Un acte comme celui de Hanau ne doit jamais se reproduire.\u00bb<\/p>","protected":false},"excerpt":{"rendered":"<p>L'attentat de Hanau ne doit jamais se r\u00e9p\u00e9ter Green Main-Kinzig: La lutte contre le racisme reste une t\u00e2che sociale \u2026<\/p>","protected":false},"author":-1,"featured_media":1571,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/posts\/1569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/comments?post=1569"}],"version-history":[{"count":4,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/posts\/1569\/revisions"}],"predecessor-version":[{"id":1576,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/posts\/1569\/revisions\/1576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/media\/1571"}],"wp:attachment":[{"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/media?parent=1569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/categories?post=1569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gruene-mkk.de\/fr\/wp-json\/wp\/v2\/tags?post=1569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}